{"id":4422,"date":"2023-11-20T09:13:26","date_gmt":"2023-11-20T09:13:26","guid":{"rendered":"https:\/\/t-umbrella.com\/stampa-digitale\/"},"modified":"2024-02-05T20:50:31","modified_gmt":"2024-02-05T20:50:31","slug":"stampa-digitale","status":"publish","type":"page","link":"https:\/\/t-umbrella.com\/it\/stampa-digitale\/","title":{"rendered":"Stampa digitale"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"4422\" class=\"elementor elementor-4422 elementor-629\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-32f8233 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"32f8233\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-75897d5\" data-id=\"75897d5\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2256b6c elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"2256b6c\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInDown&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Stampa digitale<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ef16cb7 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"ef16cb7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-eb902a4 elementor-widget__width-initial elementor-widget-mobile__width-inherit elementor-widget elementor-widget-text-editor\" data-id=\"eb902a4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Stampa digitale: La stampa digitale consente di realizzare disegni pi\u00f9 complessi e colorati. Utilizza una stampante a controllo computerizzato per applicare direttamente il disegno sul tettuccio dell&#8217;ombrellone. La stampa digitale \u00e8 ideale per motivi intricati e immagini ad alta risoluzione. Non \u00e8 richiesto un MOQ, ma il costo \u00e8 elevato.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-e06b4d1 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"e06b4d1\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-f9828ae\" data-id=\"f9828ae\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-dd33de4 elementor-widget elementor-widget-image\" data-id=\"dd33de4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/t-umbrella.com\/wp-content\/uploads\/2023\/11\/print2.png\" class=\"attachment-large size-large wp-image-2603\" alt=\"\" srcset=\"https:\/\/t-umbrella.com\/wp-content\/uploads\/2023\/11\/print2.png 500w, https:\/\/t-umbrella.com\/wp-content\/uploads\/2023\/11\/print2-300x300.png 300w, https:\/\/t-umbrella.com\/wp-content\/uploads\/2023\/11\/print2-100x100.png 100w, https:\/\/t-umbrella.com\/wp-content\/uploads\/2023\/11\/print2-150x150.png 150w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-461bfd9 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"461bfd9\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-59f7555\" data-id=\"59f7555\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e732c17 elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"e732c17\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInDown&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Vantaggi della stampa digitale:<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0122414 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"0122414\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"icon icon-umbrella\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><b>Tempi rapidi:<\/b> I tempi di allestimento minimi consentono una produzione pi\u00f9 rapida, ideale per piccole tirature e ordini rapidi.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"icon icon-umbrella\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><b>Dettaglio e precisione elevati:<\/b> Pu\u00f2 riprodurre disegni intricati, dettagli fini e sfumature uniformi.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"icon icon-umbrella\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><b>Stampa a dati variabili:<\/b> Personalizzate facilmente ogni stampa con informazioni uniche.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"icon icon-umbrella\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><b>Economico per piccole tirature:<\/b> i bassi costi di allestimento lo rendono conveniente per piccole quantit\u00e0 di stampa.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"icon icon-umbrella\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><b>Eco-compatibile:<\/b> genera meno rifiuti, utilizza meno sostanze chimiche e pu\u00f2 essere pi\u00f9 sostenibile dal punto di vista ambientale.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"icon icon-umbrella\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><b>Precisione del colore: <\/b>Consente di ottenere una riproduzione uniforme dei colori, rendendola adatta alla coerenza del marchio.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-78c81a9\" data-id=\"78c81a9\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-dd9b05e elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"dd9b05e\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInDown&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Svantaggi della stampa digitale:<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-091e0d7 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"091e0d7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"icon icon-umbrella\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><b>Durata limitata:<\/b> Gli inchiostri non hanno la stessa durata di quelli serigrafici e sono quindi meno adatti ad articoli soggetti a forte usura.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"icon icon-umbrella\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><b>Costi unitari pi\u00f9 elevati:<\/b> Meno conveniente per le grandi tirature a causa del costo unitario pi\u00f9 elevato.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"icon icon-umbrella\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><b>Costi unitari pi\u00f9 elevati: <\/b>Meno conveniente per le grandi tirature a causa del costo unitario pi\u00f9 elevato.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"icon icon-umbrella\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><b>Gamma cromatica ridotta: <\/b>la stampa digitale potrebbe non raggiungere la stessa vivacit\u00e0 dei colori della serigrafia.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"icon icon-umbrella\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><b>Velocit\u00e0 e produzione:<\/b> Pi\u00f9 lenta per progetti di stampa su larga scala o in grandi quantit\u00e0.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"icon icon-umbrella\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><b>Velocit\u00e0 e produzione:<\/b> Pi\u00f9 lenta per progetti di stampa su larga scala o in grandi quantit\u00e0.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-4d08503 elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"4d08503\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInDown&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Se non siete sicuri di quale sia l'opzione di stampa pi\u00f9 adatta al vostro progetto, lasciate che vi aiutiamo noi.<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3e26652 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"3e26652\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-lg\" href=\"https:\/\/t-umbrella.com\/contact\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">OTTENERE UN PREVENTIVO<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-0b6a84b elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"0b6a84b\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-528aad5\" data-id=\"528aad5\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-df0caf0 elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"df0caf0\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInDown&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">CONSIGLIATO PER VOI<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ebccf0c elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"ebccf0c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3f77084 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"3f77084\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-lg\" href=\"https:\/\/t-umbrella.com\/contact\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">OTTENERE UN PREVENTIVO<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5f28c30 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"5f28c30\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-c1e31eb\" data-id=\"c1e31eb\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a49dac7 elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"a49dac7\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInDown&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">PERCH\u00c9 SCEGLIERE NOI<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-16427ce elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"16427ce\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-801dfa6 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"801dfa6\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-e2eb9ee\" data-id=\"e2eb9ee\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f86e753 elementor-view-default elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"f86e753\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<a href=\"tel:+8613884437686\" class=\"elementor-icon\" tabindex=\"-1\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"icon icon-checked1\"><\/i>\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\t19 anni di produzione e progettazione di ombrelli\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-c017b3b\" data-id=\"c017b3b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2d31fa2 elementor-view-default elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"2d31fa2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<a href=\"tel:+8613884437686\" class=\"elementor-icon\" tabindex=\"-1\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"icon icon-checked1\"><\/i>\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tPi\u00f9 di 100 operai specializzati e circa 100 macchine da lavoro.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-e962340\" data-id=\"e962340\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7a498d7 elementor-view-default elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"7a498d7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<a href=\"tel:+8613884437686\" class=\"elementor-icon\" tabindex=\"-1\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"icon icon-checked1\"><\/i>\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tTempo di consegna da 3 a 5 giorni per il campione di ombrello stampato personalizzato\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-e0ac54e\" data-id=\"e0ac54e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2d8b6f6 elementor-view-default elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"2d8b6f6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<a href=\"tel:+8613884437686\" class=\"elementor-icon\" tabindex=\"-1\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"icon icon-checked1\"><\/i>\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tBSCI, ISO90001, Amazon, Alibaba e Ispezione in fabbrica guidata dal cliente\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-43772b1 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"43772b1\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-1b0ddce\" data-id=\"1b0ddce\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-10740a9 elementor-view-default elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"10740a9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<a href=\"tel:+8613884437686\" class=\"elementor-icon\" tabindex=\"-1\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"icon icon-checked1\"><\/i>\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\t15-25 giorni di tempo per la produzione di massa\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-777b9cf\" data-id=\"777b9cf\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-20de348 elementor-view-default elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"20de348\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<a href=\"tel:+8613884437686\" class=\"elementor-icon\" tabindex=\"-1\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"icon icon-checked1\"><\/i>\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tApparecchiature di prova avanzate per il test di pressione idrostatica, il test del colore della sorgente luminosa, il test di resistenza alle alte temperature, il test di nebbia salina, il test push-pull, il test di apertura e chiusura automatica.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-4097f02\" data-id=\"4097f02\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f46c4d2 elementor-view-default elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"f46c4d2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<a href=\"tel:+8613884437686\" class=\"elementor-icon\" tabindex=\"-1\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"icon icon-checked1\"><\/i>\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tVendite top-one e cinque stelle sulla piattaforma B to B\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-02cb756\" data-id=\"02cb756\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-072743e elementor-view-default elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"072743e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<a href=\"tel:+8613884437686\" class=\"elementor-icon\" tabindex=\"-1\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"icon icon-checked1\"><\/i>\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tDesign creativo e ricerca dell'alta qualit\u00e0 e dell'uso di materiali ecologici: R-PET\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-58e23a6 elementor-section-full_width elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"58e23a6\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;motion_fx_motion_fx_scrolling&quot;:&quot;yes&quot;,&quot;motion_fx_translateY_effect&quot;:&quot;yes&quot;,&quot;motion_fx_translateY_direction&quot;:&quot;negative&quot;,&quot;motion_fx_translateY_speed&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;1.5&quot;,&quot;sizes&quot;:[]},&quot;motion_fx_translateY_affectedRange&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:{&quot;start&quot;:&quot;0&quot;,&quot;end&quot;:&quot;50&quot;}},&quot;motion_fx_devices&quot;:[&quot;desktop&quot;]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-0cea6eb\" data-id=\"0cea6eb\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9de0af9 elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"9de0af9\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInDown&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Blog consigliati\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-8e4c38d elementor-section-full_width elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"8e4c38d\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-9aed5a0\" data-id=\"9aed5a0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-817ca92 elementor-posts__hover-none elementor-grid-tablet-3 elementor-grid-3 elementor-grid-mobile-1 elementor-posts--thumbnail-top elementor-widget elementor-widget-posts\" data-id=\"817ca92\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;cards_row_gap&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;50&quot;,&quot;sizes&quot;:[]},&quot;cards_columns_tablet&quot;:&quot;3&quot;,&quot;cards_columns&quot;:&quot;3&quot;,&quot;cards_columns_mobile&quot;:&quot;1&quot;,&quot;cards_row_gap_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;cards_row_gap_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"posts.cards\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-posts-container elementor-posts elementor-posts--skin-cards elementor-grid\" role=\"list\">\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-4704 post type-post status-publish format-standard has-post-thumbnail hentry category-non-categorizzato\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/t-umbrella.com\/it\/moda-per-i-giorni-di-pioggia-opzioni-di-ombrelli-alla-moda-per-ogni-stagione\/\" tabindex=\"-1\" ><div class=\"elementor-post__thumbnail\"><img decoding=\"async\" width=\"1000\" height=\"667\" src=\"https:\/\/t-umbrella.com\/wp-content\/uploads\/2023\/11\/20231101111150994-min.jpg\" class=\"attachment-full size-full wp-image-2369\" alt=\"\" srcset=\"https:\/\/t-umbrella.com\/wp-content\/uploads\/2023\/11\/20231101111150994-min.jpg 1000w, https:\/\/t-umbrella.com\/wp-content\/uploads\/2023\/11\/20231101111150994-min-600x400.jpg 600w, https:\/\/t-umbrella.com\/wp-content\/uploads\/2023\/11\/20231101111150994-min-300x200.jpg 300w, https:\/\/t-umbrella.com\/wp-content\/uploads\/2023\/11\/20231101111150994-min-768x512.jpg 768w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><\/div><\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/t-umbrella.com\/it\/moda-per-i-giorni-di-pioggia-opzioni-di-ombrelli-alla-moda-per-ogni-stagione\/\" >\n\t\t\t\tModa per i giorni di pioggia: Opzioni di ombrelli alla moda per ogni stagione\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\t18 Novembre 2023\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-4522 post type-post status-publish format-standard has-post-thumbnail hentry category-non-categorizzato\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/t-umbrella.com\/it\/maniglia-per-ombrello\/\" tabindex=\"-1\" ><div class=\"elementor-post__thumbnail\"><img decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/t-umbrella.com\/wp-content\/uploads\/2023\/11\/20231030155212373-min.png\" class=\"attachment-full size-full wp-image-2351\" alt=\"\" srcset=\"https:\/\/t-umbrella.com\/wp-content\/uploads\/2023\/11\/20231030155212373-min.png 800w, https:\/\/t-umbrella.com\/wp-content\/uploads\/2023\/11\/20231030155212373-min-300x300.png 300w, https:\/\/t-umbrella.com\/wp-content\/uploads\/2023\/11\/20231030155212373-min-100x100.png 100w, https:\/\/t-umbrella.com\/wp-content\/uploads\/2023\/11\/20231030155212373-min-600x600.png 600w, https:\/\/t-umbrella.com\/wp-content\/uploads\/2023\/11\/20231030155212373-min-150x150.png 150w, https:\/\/t-umbrella.com\/wp-content\/uploads\/2023\/11\/20231030155212373-min-768x768.png 768w, https:\/\/t-umbrella.com\/wp-content\/uploads\/2023\/11\/20231030155212373-min-700x700.png 700w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/div><\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/t-umbrella.com\/it\/maniglia-per-ombrello\/\" >\n\t\t\t\tManiglia per ombrello\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\t18 Novembre 2023\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-4808 post type-post status-publish format-standard has-post-thumbnail hentry category-non-categorizzato\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/t-umbrella.com\/it\/come-sono-fatti-gli-ombrelli-una-guida-completa\/\" tabindex=\"-1\" ><div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/t-umbrella.com\/wp-content\/uploads\/2024\/01\/1911705044703_.pic_.jpg\" class=\"attachment-full size-full wp-image-3407\" alt=\"\" srcset=\"https:\/\/t-umbrella.com\/wp-content\/uploads\/2024\/01\/1911705044703_.pic_.jpg 800w, https:\/\/t-umbrella.com\/wp-content\/uploads\/2024\/01\/1911705044703_.pic_-300x300.jpg 300w, https:\/\/t-umbrella.com\/wp-content\/uploads\/2024\/01\/1911705044703_.pic_-100x100.jpg 100w, https:\/\/t-umbrella.com\/wp-content\/uploads\/2024\/01\/1911705044703_.pic_-600x600.jpg 600w, https:\/\/t-umbrella.com\/wp-content\/uploads\/2024\/01\/1911705044703_.pic_-150x150.jpg 150w, https:\/\/t-umbrella.com\/wp-content\/uploads\/2024\/01\/1911705044703_.pic_-768x768.jpg 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/div><\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/t-umbrella.com\/it\/come-sono-fatti-gli-ombrelli-una-guida-completa\/\" >\n\t\t\t\tCome sono fatti gli ombrelli: una guida completa\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\t26 Gennaio 2024\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<\/div>\n\t\t\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6f96d99 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"6f96d99\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-lg\" href=\"https:\/\/t-umbrella.com\/contact\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">OTTENERE UN PREVENTIVO<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Stampa digitale Stampa digitale: La stampa digitale consente di realizzare disegni pi\u00f9 complessi e colorati. Utilizza una stampante a controllo computerizzato per applicare direttamente il disegno sul tettuccio dell&#8217;ombrellone. La stampa digitale \u00e8 ideale per motivi intricati e immagini ad alta risoluzione. Non \u00e8 richiesto un MOQ, ma il costo \u00e8 elevato. Vantaggi della stampa digitale: Tempi rapidi: I tempi di allestimento minimi consentono una produzione pi\u00f9 rapida, ideale per piccole tirature e ordini rapidi. Dettaglio e precisione elevati: Pu\u00f2 riprodurre disegni intricati, dettagli fini e sfumature uniformi. Stampa a dati variabili: Personalizzate facilmente ogni stampa con informazioni uniche. Economico per piccole tirature: i bassi costi di allestimento lo rendono conveniente per piccole quantit\u00e0 di stampa. Eco-compatibile: genera meno rifiuti, utilizza meno sostanze chimiche e pu\u00f2 essere pi\u00f9 sostenibile dal punto di vista ambientale. Precisione del colore: Consente di ottenere una riproduzione uniforme dei colori, rendendola adatta alla coerenza del marchio. Svantaggi della stampa digitale: Durata limitata: Gli inchiostri non hanno la stessa durata di quelli serigrafici e sono quindi meno adatti ad articoli soggetti a forte usura. Costi unitari pi\u00f9 elevati: Meno conveniente per le grandi tirature a causa del costo unitario pi\u00f9 elevato. Costi unitari pi\u00f9 elevati: Meno conveniente per le grandi tirature a causa del costo unitario pi\u00f9 elevato. Gamma cromatica ridotta: la stampa digitale potrebbe non raggiungere la stessa vivacit\u00e0 dei colori della serigrafia. Velocit\u00e0 e produzione: Pi\u00f9 lenta per progetti di stampa su larga scala o in grandi quantit\u00e0. Velocit\u00e0 e produzione: Pi\u00f9 lenta per progetti di stampa su larga scala o in grandi quantit\u00e0. Se non siete sicuri di quale sia l&#8217;opzione di stampa pi\u00f9 adatta al vostro progetto, lasciate che vi aiutiamo noi. OTTENERE UN PREVENTIVO CONSIGLIATO PER VOI Stampa serigrafica Stampa serigrafica Stampa a trasferimento termico Stampa a trasferimento termico Stampa all over Stampa all over OTTENERE UN PREVENTIVO PERCH\u00c9 SCEGLIERE NOI 19 anni di produzione e progettazione di ombrelli Pi\u00f9 di 100 operai specializzati e circa 100 macchine da lavoro. Tempo di consegna da 3 a 5 giorni per il campione di ombrello stampato personalizzato BSCI, ISO90001, Amazon, Alibaba e Ispezione in fabbrica guidata dal cliente 15-25 giorni di tempo per la produzione di massa Apparecchiature di prova avanzate per il test di pressione idrostatica, il test del colore della sorgente luminosa, il test di resistenza alle alte temperature, il test di nebbia salina, il test push-pull, il test di apertura e chiusura automatica. Vendite top-one e cinque stelle sulla piattaforma B to B Design creativo e ricerca dell&#8217;alta qualit\u00e0 e dell&#8217;uso di materiali ecologici: R-PET Blog consigliati OTTENERE UN PREVENTIVO<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","_seopress_robots_follow":"","_seopress_robots_imageindex":"","_seopress_robots_snippet":"","_seopress_robots_primary_cat":"","_seopress_robots_breadcrumbs":"","_seopress_robots_freeze_modified_date":"","_seopress_robots_custom_modified_date":"","_seopress_robots_canonical":"","_seopress_social_fb_title":"","_seopress_social_fb_desc":"","_seopress_social_fb_img":"","_seopress_social_fb_img_attachment_id":0,"_seopress_social_fb_img_width":0,"_seopress_social_fb_img_height":0,"_seopress_social_twitter_title":"","_seopress_social_twitter_desc":"","_seopress_social_twitter_img":"","_seopress_social_twitter_img_attachment_id":0,"_seopress_social_twitter_img_width":0,"_seopress_social_twitter_img_height":0,"_seopress_redirections_value":"","_seopress_redirections_enabled":"","_seopress_redirections_enabled_regex":"","_seopress_redirections_logged_status":"","_seopress_redirections_param":"","_seopress_redirections_type":0,"_seopress_analysis_target_kw":"","footnotes":""},"class_list":["post-4422","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Stampa digitale - T-Umbrella<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/t-umbrella.com\/it\/stampa-digitale\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Stampa digitale - T-Umbrella\" \/>\n<meta property=\"og:description\" content=\"Stampa digitale Stampa digitale: La stampa digitale consente di realizzare disegni pi\u00f9 complessi e colorati. Utilizza una stampante a controllo computerizzato per applicare direttamente il disegno sul tettuccio dell&#8217;ombrellone. La stampa digitale \u00e8 ideale per motivi intricati e immagini ad alta risoluzione. Non \u00e8 richiesto un MOQ, ma il costo \u00e8 elevato. Vantaggi della stampa digitale: Tempi rapidi: I tempi di allestimento minimi consentono una produzione pi\u00f9 rapida, ideale per piccole tirature e ordini rapidi. Dettaglio e precisione elevati: Pu\u00f2 riprodurre disegni intricati, dettagli fini e sfumature uniformi. Stampa a dati variabili: Personalizzate facilmente ogni stampa con informazioni uniche. Economico per piccole tirature: i bassi costi di allestimento lo rendono conveniente per piccole quantit\u00e0 di stampa. Eco-compatibile: genera meno rifiuti, utilizza meno sostanze chimiche e pu\u00f2 essere pi\u00f9 sostenibile dal punto di vista ambientale. Precisione del colore: Consente di ottenere una riproduzione uniforme dei colori, rendendola adatta alla coerenza del marchio. Svantaggi della stampa digitale: Durata limitata: Gli inchiostri non hanno la stessa durata di quelli serigrafici e sono quindi meno adatti ad articoli soggetti a forte usura. Costi unitari pi\u00f9 elevati: Meno conveniente per le grandi tirature a causa del costo unitario pi\u00f9 elevato. Costi unitari pi\u00f9 elevati: Meno conveniente per le grandi tirature a causa del costo unitario pi\u00f9 elevato. Gamma cromatica ridotta: la stampa digitale potrebbe non raggiungere la stessa vivacit\u00e0 dei colori della serigrafia. Velocit\u00e0 e produzione: Pi\u00f9 lenta per progetti di stampa su larga scala o in grandi quantit\u00e0. Velocit\u00e0 e produzione: Pi\u00f9 lenta per progetti di stampa su larga scala o in grandi quantit\u00e0. Se non siete sicuri di quale sia l&#8217;opzione di stampa pi\u00f9 adatta al vostro progetto, lasciate che vi aiutiamo noi. OTTENERE UN PREVENTIVO CONSIGLIATO PER VOI Stampa serigrafica Stampa serigrafica Stampa a trasferimento termico Stampa a trasferimento termico Stampa all over Stampa all over OTTENERE UN PREVENTIVO PERCH\u00c9 SCEGLIERE NOI 19 anni di produzione e progettazione di ombrelli Pi\u00f9 di 100 operai specializzati e circa 100 macchine da lavoro. Tempo di consegna da 3 a 5 giorni per il campione di ombrello stampato personalizzato BSCI, ISO90001, Amazon, Alibaba e Ispezione in fabbrica guidata dal cliente 15-25 giorni di tempo per la produzione di massa Apparecchiature di prova avanzate per il test di pressione idrostatica, il test del colore della sorgente luminosa, il test di resistenza alle alte temperature, il test di nebbia salina, il test push-pull, il test di apertura e chiusura automatica. Vendite top-one e cinque stelle sulla piattaforma B to B Design creativo e ricerca dell&#8217;alta qualit\u00e0 e dell&#8217;uso di materiali ecologici: R-PET Blog consigliati OTTENERE UN PREVENTIVO\" \/>\n<meta property=\"og:url\" content=\"https:\/\/t-umbrella.com\/it\/stampa-digitale\/\" \/>\n<meta property=\"og:site_name\" content=\"T-Umbrella\" \/>\n<meta property=\"article:modified_time\" content=\"2024-02-05T20:50:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/t-umbrella.com\/wp-content\/uploads\/2023\/11\/print2.png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/t-umbrella.com\\\/it\\\/stampa-digitale\\\/\",\"url\":\"https:\\\/\\\/t-umbrella.com\\\/it\\\/stampa-digitale\\\/\",\"name\":\"Stampa digitale - T-Umbrella\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/t-umbrella.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/t-umbrella.com\\\/it\\\/stampa-digitale\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/t-umbrella.com\\\/it\\\/stampa-digitale\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/t-umbrella.com\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/print2.png\",\"datePublished\":\"2023-11-20T09:13:26+00:00\",\"dateModified\":\"2024-02-05T20:50:31+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/t-umbrella.com\\\/it\\\/stampa-digitale\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/t-umbrella.com\\\/it\\\/stampa-digitale\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/t-umbrella.com\\\/it\\\/stampa-digitale\\\/#primaryimage\",\"url\":\"https:\\\/\\\/t-umbrella.com\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/print2.png\",\"contentUrl\":\"https:\\\/\\\/t-umbrella.com\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/print2.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/t-umbrella.com\\\/it\\\/stampa-digitale\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/t-umbrella.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Stampa digitale\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/t-umbrella.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/t-umbrella.com\\\/it\\\/\",\"name\":\"T-Umbrella\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/t-umbrella.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/t-umbrella.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/t-umbrella.com\\\/it\\\/#organization\",\"name\":\"T-Umbrella\",\"url\":\"https:\\\/\\\/t-umbrella.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/t-umbrella.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/t-umbrella.com\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/logo.png\",\"contentUrl\":\"https:\\\/\\\/t-umbrella.com\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/logo.png\",\"width\":300,\"height\":120,\"caption\":\"T-Umbrella\"},\"image\":{\"@id\":\"https:\\\/\\\/t-umbrella.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Stampa digitale - T-Umbrella","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/t-umbrella.com\/it\/stampa-digitale\/","og_locale":"it_IT","og_type":"article","og_title":"Stampa digitale - T-Umbrella","og_description":"Stampa digitale Stampa digitale: La stampa digitale consente di realizzare disegni pi\u00f9 complessi e colorati. Utilizza una stampante a controllo computerizzato per applicare direttamente il disegno sul tettuccio dell&#8217;ombrellone. La stampa digitale \u00e8 ideale per motivi intricati e immagini ad alta risoluzione. Non \u00e8 richiesto un MOQ, ma il costo \u00e8 elevato. Vantaggi della stampa digitale: Tempi rapidi: I tempi di allestimento minimi consentono una produzione pi\u00f9 rapida, ideale per piccole tirature e ordini rapidi. Dettaglio e precisione elevati: Pu\u00f2 riprodurre disegni intricati, dettagli fini e sfumature uniformi. Stampa a dati variabili: Personalizzate facilmente ogni stampa con informazioni uniche. Economico per piccole tirature: i bassi costi di allestimento lo rendono conveniente per piccole quantit\u00e0 di stampa. Eco-compatibile: genera meno rifiuti, utilizza meno sostanze chimiche e pu\u00f2 essere pi\u00f9 sostenibile dal punto di vista ambientale. Precisione del colore: Consente di ottenere una riproduzione uniforme dei colori, rendendola adatta alla coerenza del marchio. Svantaggi della stampa digitale: Durata limitata: Gli inchiostri non hanno la stessa durata di quelli serigrafici e sono quindi meno adatti ad articoli soggetti a forte usura. Costi unitari pi\u00f9 elevati: Meno conveniente per le grandi tirature a causa del costo unitario pi\u00f9 elevato. Costi unitari pi\u00f9 elevati: Meno conveniente per le grandi tirature a causa del costo unitario pi\u00f9 elevato. Gamma cromatica ridotta: la stampa digitale potrebbe non raggiungere la stessa vivacit\u00e0 dei colori della serigrafia. Velocit\u00e0 e produzione: Pi\u00f9 lenta per progetti di stampa su larga scala o in grandi quantit\u00e0. Velocit\u00e0 e produzione: Pi\u00f9 lenta per progetti di stampa su larga scala o in grandi quantit\u00e0. Se non siete sicuri di quale sia l&#8217;opzione di stampa pi\u00f9 adatta al vostro progetto, lasciate che vi aiutiamo noi. OTTENERE UN PREVENTIVO CONSIGLIATO PER VOI Stampa serigrafica Stampa serigrafica Stampa a trasferimento termico Stampa a trasferimento termico Stampa all over Stampa all over OTTENERE UN PREVENTIVO PERCH\u00c9 SCEGLIERE NOI 19 anni di produzione e progettazione di ombrelli Pi\u00f9 di 100 operai specializzati e circa 100 macchine da lavoro. Tempo di consegna da 3 a 5 giorni per il campione di ombrello stampato personalizzato BSCI, ISO90001, Amazon, Alibaba e Ispezione in fabbrica guidata dal cliente 15-25 giorni di tempo per la produzione di massa Apparecchiature di prova avanzate per il test di pressione idrostatica, il test del colore della sorgente luminosa, il test di resistenza alle alte temperature, il test di nebbia salina, il test push-pull, il test di apertura e chiusura automatica. Vendite top-one e cinque stelle sulla piattaforma B to B Design creativo e ricerca dell&#8217;alta qualit\u00e0 e dell&#8217;uso di materiali ecologici: R-PET Blog consigliati OTTENERE UN PREVENTIVO","og_url":"https:\/\/t-umbrella.com\/it\/stampa-digitale\/","og_site_name":"T-Umbrella","article_modified_time":"2024-02-05T20:50:31+00:00","og_image":[{"url":"https:\/\/t-umbrella.com\/wp-content\/uploads\/2023\/11\/print2.png","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/t-umbrella.com\/it\/stampa-digitale\/","url":"https:\/\/t-umbrella.com\/it\/stampa-digitale\/","name":"Stampa digitale - T-Umbrella","isPartOf":{"@id":"https:\/\/t-umbrella.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/t-umbrella.com\/it\/stampa-digitale\/#primaryimage"},"image":{"@id":"https:\/\/t-umbrella.com\/it\/stampa-digitale\/#primaryimage"},"thumbnailUrl":"https:\/\/t-umbrella.com\/wp-content\/uploads\/2023\/11\/print2.png","datePublished":"2023-11-20T09:13:26+00:00","dateModified":"2024-02-05T20:50:31+00:00","breadcrumb":{"@id":"https:\/\/t-umbrella.com\/it\/stampa-digitale\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/t-umbrella.com\/it\/stampa-digitale\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/t-umbrella.com\/it\/stampa-digitale\/#primaryimage","url":"https:\/\/t-umbrella.com\/wp-content\/uploads\/2023\/11\/print2.png","contentUrl":"https:\/\/t-umbrella.com\/wp-content\/uploads\/2023\/11\/print2.png"},{"@type":"BreadcrumbList","@id":"https:\/\/t-umbrella.com\/it\/stampa-digitale\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/t-umbrella.com\/it\/"},{"@type":"ListItem","position":2,"name":"Stampa digitale"}]},{"@type":"WebSite","@id":"https:\/\/t-umbrella.com\/it\/#website","url":"https:\/\/t-umbrella.com\/it\/","name":"T-Umbrella","description":"","publisher":{"@id":"https:\/\/t-umbrella.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/t-umbrella.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/t-umbrella.com\/it\/#organization","name":"T-Umbrella","url":"https:\/\/t-umbrella.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/t-umbrella.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/t-umbrella.com\/wp-content\/uploads\/2023\/11\/logo.png","contentUrl":"https:\/\/t-umbrella.com\/wp-content\/uploads\/2023\/11\/logo.png","width":300,"height":120,"caption":"T-Umbrella"},"image":{"@id":"https:\/\/t-umbrella.com\/it\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/t-umbrella.com\/it\/wp-json\/wp\/v2\/pages\/4422","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/t-umbrella.com\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/t-umbrella.com\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/t-umbrella.com\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/t-umbrella.com\/it\/wp-json\/wp\/v2\/comments?post=4422"}],"version-history":[{"count":1,"href":"https:\/\/t-umbrella.com\/it\/wp-json\/wp\/v2\/pages\/4422\/revisions"}],"predecessor-version":[{"id":4435,"href":"https:\/\/t-umbrella.com\/it\/wp-json\/wp\/v2\/pages\/4422\/revisions\/4435"}],"wp:attachment":[{"href":"https:\/\/t-umbrella.com\/it\/wp-json\/wp\/v2\/media?parent=4422"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}